{"id":44122,"date":"2025-11-17T11:41:51","date_gmt":"2025-11-17T10:41:51","guid":{"rendered":"https:\/\/seaottereurope.com\/?page_id=44122"},"modified":"2026-07-29T10:13:41","modified_gmt":"2026-07-29T08:13:41","slug":"mtb-classic-sea-otter-europe","status":"publish","type":"page","link":"https:\/\/www.seaottereurope.com\/es\/mtb-classic-sea-otter-europe\/","title":{"rendered":"MTB Classic Sea Otter Europe"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"44122\" class=\"elementor elementor-44122\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebffa4b e-flex e-con-boxed e-con e-parent\" data-id=\"ebffa4b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-703ad17 e-con-full e-flex e-con e-child\" data-id=\"703ad17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e06396f e-con-full e-flex e-con e-child\" data-id=\"e06396f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cc7ae3 elementor-widget elementor-widget-the7-heading\" data-id=\"8cc7ae3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"the7-heading-title elementor-size-default\">Nos encantan las tradiciones, \u00a1nos encanta MTB Classic!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b1f9bc elementor-widget elementor-widget-text-editor\" data-id=\"8b1f9bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ser \u00ab<strong>old school<\/strong>\u00bb est\u00e1 de moda. Ven\u00a0<strong>con tu bicicleta<\/strong>\u00a0cl\u00e1sica y \u00fanete a nosotros\u00a0<strong>para hacer historia<\/strong>. Queremos que este legado crezca.<\/p><p>Si tienes una bici antes de 1996, no te lo pienses, participa y divi\u00e9rtete, pero si no, ven y disfruta de esas bicis con las que empez\u00f3 el deporte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da733fb elementor-widget elementor-widget-the7_button_widget\" data-id=\"da733fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7_button_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\"><a href=\"https:\/\/www.rockthesport.com\/es\/evento\/mtb-classic-sea-otter-europe-2026\/inscripcion\/selecciona-tarifa\" target=\"_blank\" class=\"box-button elementor-button elementor-size-lg\" rel=\"noopener\">INSCRIPCIONES<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-362d0ac e-con-full e-flex e-con e-child\" data-id=\"362d0ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d82b786 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d82b786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">S\u00e1bado, 19 Septiembre<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">18:30h<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-euro-sign\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M310.706 413.765c-1.314-6.63-7.835-10.872-14.424-9.369-10.692 2.439-27.422 5.413-45.426 5.413-56.763 0-101.929-34.79-121.461-85.449h113.689a12 12 0 0 0 11.708-9.369l6.373-28.36c1.686-7.502-4.019-14.631-11.708-14.631H115.22c-1.21-14.328-1.414-28.287.137-42.245H261.95a12 12 0 0 0 11.723-9.434l6.512-29.755c1.638-7.484-4.061-14.566-11.723-14.566H130.184c20.633-44.991 62.69-75.03 117.619-75.03 14.486 0 28.564 2.25 37.851 4.145 6.216 1.268 12.347-2.498 14.002-8.623l11.991-44.368c1.822-6.741-2.465-13.616-9.326-14.917C290.217 34.912 270.71 32 249.635 32 152.451 32 74.03 92.252 45.075 176H12c-6.627 0-12 5.373-12 12v29.755c0 6.627 5.373 12 12 12h21.569c-1.009 13.607-1.181 29.287-.181 42.245H12c-6.627 0-12 5.373-12 12v28.36c0 6.627 5.373 12 12 12h30.114C67.139 414.692 145.264 480 249.635 480c26.301 0 48.562-4.544 61.101-7.788 6.167-1.595 10.027-7.708 8.788-13.957l-8.818-44.49z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gratuita<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-pin\" viewBox=\"0 0 288 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M112 316.94v156.69l22.02 33.02c4.75 7.12 15.22 7.12 19.97 0L176 473.63V316.94c-10.39 1.92-21.06 3.06-32 3.06s-21.61-1.14-32-3.06zM144 0C64.47 0 0 64.47 0 144s64.47 144 144 144 144-64.47 144-144S223.53 0 144 0zm0 76c-37.5 0-68 30.5-68 68 0 6.62-5.38 12-12 12s-12-5.38-12-12c0-50.73 41.28-92 92-92 6.62 0 12 5.38 12 12s-5.38 12-12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Arco de salida de la Shimano Super Cup Massi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bicycle\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512.509 192.001c-16.373-.064-32.03 2.955-46.436 8.495l-77.68-125.153A24 24 0 0 0 368.001 64h-64c-8.837 0-16 7.163-16 16v16c0 8.837 7.163 16 16 16h50.649l14.896 24H256.002v-16c0-8.837-7.163-16-16-16h-87.459c-13.441 0-24.777 10.999-24.536 24.437.232 13.044 10.876 23.563 23.995 23.563h48.726l-29.417 47.52c-13.433-4.83-27.904-7.483-42.992-7.52C58.094 191.83.412 249.012.002 319.236-.413 390.279 57.055 448 128.002 448c59.642 0 109.758-40.793 123.967-96h52.033a24 24 0 0 0 20.406-11.367L410.37 201.77l14.938 24.067c-25.455 23.448-41.385 57.081-41.307 94.437.145 68.833 57.899 127.051 126.729 127.719 70.606.685 128.181-55.803 129.255-125.996 1.086-70.941-56.526-129.72-127.476-129.996zM186.75 265.772c9.727 10.529 16.673 23.661 19.642 38.228h-43.306l23.664-38.228zM128.002 400c-44.112 0-80-35.888-80-80s35.888-80 80-80c5.869 0 11.586.653 17.099 1.859l-45.505 73.509C89.715 331.327 101.213 352 120.002 352h81.3c-12.37 28.225-40.562 48-73.3 48zm162.63-96h-35.624c-3.96-31.756-19.556-59.894-42.383-80.026L237.371 184h127.547l-74.286 120zm217.057 95.886c-41.036-2.165-74.049-35.692-75.627-76.755-.812-21.121 6.633-40.518 19.335-55.263l44.433 71.586c4.66 7.508 14.524 9.816 22.032 5.156l13.594-8.437c7.508-4.66 9.817-14.524 5.156-22.032l-44.468-71.643a79.901 79.901 0 0 1 19.858-2.497c44.112 0 80 35.888 80 80-.001 45.54-38.252 82.316-84.313 79.885z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Modelos de bicicleta MTB cl\u00e1sicos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-flag-checkered\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M243.2 189.9V258c26.1 5.9 49.3 15.6 73.6 22.3v-68.2c-26-5.8-49.4-15.5-73.6-22.2zm223.3-123c-34.3 15.9-76.5 31.9-117 31.9C296 98.8 251.7 64 184.3 64c-25 0-47.3 4.4-68 12 2.8-7.3 4.1-15.2 3.6-23.6C118.1 24 94.8 1.2 66.3 0 34.3-1.3 8 24.3 8 56c0 19 9.5 35.8 24 45.9V488c0 13.3 10.7 24 24 24h16c13.3 0 24-10.7 24-24v-94.4c28.3-12.1 63.6-22.1 114.4-22.1 53.6 0 97.8 34.8 165.2 34.8 48.2 0 86.7-16.3 122.5-40.9 8.7-6 13.8-15.8 13.8-26.4V95.9c.1-23.3-24.2-38.8-45.4-29zM169.6 325.5c-25.8 2.7-50 8.2-73.6 16.6v-70.5c26.2-9.3 47.5-15 73.6-17.4zM464 191c-23.6 9.8-46.3 19.5-73.6 23.9V286c24.8-3.4 51.4-11.8 73.6-26v70.5c-25.1 16.1-48.5 24.7-73.6 27.1V286c-27 3.7-47.9 1.5-73.6-5.6v67.4c-23.9-7.4-47.3-16.7-73.6-21.3V258c-19.7-4.4-40.8-6.8-73.6-3.8v-70c-22.4 3.1-44.6 10.2-73.6 20.9v-70.5c33.2-12.2 50.1-19.8 73.6-22v71.6c27-3.7 48.4-1.3 73.6 5.7v-67.4c23.7 7.4 47.2 16.7 73.6 21.3v68.4c23.7 5.3 47.6 6.9 73.6 2.7V143c27-4.8 52.3-13.6 73.6-22.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Prueba no competitiva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8dddbb4 elementor-widget elementor-widget-heading\" data-id=\"8dddbb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RECOGIDA DE DORSALES \nDENTRO DEL PABELL\u00d3N MUNICIPAL FONTAJAU, GIRONA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3f26b1 elementor-widget elementor-widget-text-editor\" data-id=\"b3f26b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Viernes: 16.00h &#8211; 19.15h<br \/>S\u00e1bado: 09.00h &#8211; 16.30h\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fe3334 e-flex e-con-boxed e-con e-child\" data-id=\"4fe3334\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1109c6 content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"a1109c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201500%201000&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"Escena de ciclistas y bicicletas de BTT alineadas en una carrera del Sea Otter Europe, evento internacional de ciclismo celebrado en Girona\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"--ratio: 1500 \/ 1000;\" data-src=\"https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-002-R-min.jpg\" loading=\"eager\" data-srcset=\"https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-002-R-min.jpg 1500w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-002-R-min-300x200.jpg 300w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-002-R-min-1024x683.jpg 1024w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-002-R-min-768x512.jpg 768w\" \/><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd49be6 elementor-widget__width-initial content-align-left the7-hover-visibility-disabled transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"dd49be6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1500\" height=\"2250\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201500%202250&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"Imagen de fondo de la prueba deportiva de Sea Otter Europe: MTB Classic\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"--ratio: 1500 \/ 2250;\" data-src=\"https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/SEA-OTTER-EUROPE_MTB-CLASSIC-min.jpg\" loading=\"eager\" data-srcset=\"https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/SEA-OTTER-EUROPE_MTB-CLASSIC-min.jpg 1500w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/SEA-OTTER-EUROPE_MTB-CLASSIC-min-200x300.jpg 200w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/SEA-OTTER-EUROPE_MTB-CLASSIC-min-683x1024.jpg 683w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/SEA-OTTER-EUROPE_MTB-CLASSIC-min-768x1152.jpg 768w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/SEA-OTTER-EUROPE_MTB-CLASSIC-min-1024x1536.jpg 1024w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/SEA-OTTER-EUROPE_MTB-CLASSIC-min-1365x2048.jpg 1365w\" \/><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e577d53 e-con-full e-flex e-con e-child\" data-id=\"e577d53\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-26afbe3 e-con-full e-flex e-con e-child\" data-id=\"26afbe3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39e547f elementor-widget elementor-widget-the7-heading\" data-id=\"39e547f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"the7-heading-title elementor-size-default\">Qu\u00e9 incluye la inscripci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-322e825 e-con-full e-flex e-con e-child\" data-id=\"322e825\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65a978d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"65a978d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Derecho participaci\u00f3n en la MTB CLASSIC<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entrada en el recinto del festival<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dorsal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cronometraje (sin chip, pero crono manual con Clasificaci\u00f3n)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Recorrido marcado completamente<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Asistencia m\u00e9dica (Servicios m\u00e9dicos y ambulancia)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c1rea de lavado de bicicletas con hidro-limpiadoras a la llegada<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Regalo conmemorativa de la prueba (obsequio)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"56\" height=\"56\" fill=\"#000000\" viewBox=\"0 0 256 256\"><path d=\"M224.49,136.49l-72,72a12,12,0,0,1-17-17L187,140H40a12,12,0,0,1,0-24H187L135.51,64.48a12,12,0,0,1,17-17l72,72A12,12,0,0,1,224.49,136.49Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Avituallamiento legada (l\u00edquido)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b426a5c e-con-full e-flex e-con e-child\" data-id=\"b426a5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5fa0511 e-con-full e-flex e-con e-child\" data-id=\"5fa0511\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b04c98b elementor-widget elementor-widget-the7-heading\" data-id=\"b04c98b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"the7-heading-title elementor-size-default\">Normativa de la prueba<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c63fcc5 e-con-full e-flex e-con e-child\" data-id=\"c63fcc5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-091646f elementor-widget elementor-widget-text-editor\" data-id=\"091646f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Art. 1 \u2013<\/strong> La MTB Classic es una prueba deportiva de bicicleta cl\u00e1sica de mountain bike. La MTB Classic es una prueba competitiva que se desarrollar\u00e1 en el un circuito de Cross Country de 4,5km. La MTB Classic est\u00e1 organizada por el Club Deportivo Bike Catalunya, dentro del festival Sea Otter Europe.<\/p><p><strong>Art. 2.-<\/strong> La MTB Classic tendr\u00e1 la salida oficial el s\u00e1bado d\u00eda 19\/9\/26 a las 18.30h en el arco de la Super Cup Massi (en la zona verde del Pabell\u00f3n Fontajau) en el marco de la Sea Otter Europe.<\/p><p><strong>Art. 3.-<\/strong> Derecho de inscripci\u00f3n.<\/p><p><b>a)<\/b> <u>Apertura y cierre inscripciones:<\/u> Las inscripciones se abrir\u00e1n el d\u00eda 11\/06\/2026 a las 12.00h y quedar\u00e1n abiertas hasta el 18\/09\/2026 a las 23:59h. La inscripci\u00f3n es personal e intransferible y supone la aceptaci\u00f3n de todos los art\u00edculos del presente reglamento.<\/p><p><b>b)<\/b> <u>Precio de la inscripci\u00f3n:<\/u> gratuita. La inscripci\u00f3n incluye: derecho a participaci\u00f3n en la MTB Classic, entrada al recinto del festival, dorsal, cronometraje (sin chip, pero crono manual con clasificaci\u00f3n), recorrido marcado totalmente, asistencia m\u00e9dica (servicios m\u00e9dicos y ambulancia), zona de lavado de bicicletas, regalo conmemorativo de la prueba (obsequio) y avituallamiento a la llegada (l\u00edquido).<\/p><p><b>c)<\/b> <u>Recogida de dorsales:<\/u> 18\/9\/2026: 9:00h-19:15h y 19\/9\/2026: 9:00h-16:30h \u2013 Interior pabell\u00f3n municipal Fontajau. Para recoger el dorsal ES OBLIGATORIO presentar el DNI o NIE.<\/p><p><b>d)<\/b> <u>Forma de inscripci\u00f3n:<\/u> Las inscripciones se realizar\u00e1n mediante la pasarela de pago de RockTheSport. La inscripci\u00f3n es gratuita, pero se necesitar\u00e1 el registro del participante para asegurarlo en caso de accidente.<\/p><p><b>e)<\/b> <u>Responsabilidad del participante:<\/u> La participaci\u00f3n en la prueba est\u00e1 bajo la responsabilidad y propio riesgo del participante. El participante en el momento de su inscripci\u00f3n manifiesta encontrarse f\u00edsicamente apto para la prueba.<\/p><p><strong>Art. 4.-<\/strong> La organizaci\u00f3n dispondr\u00e1, durante el desarrollo de la prueba de un PMA (Punto M\u00e9dico Avanzado).<\/p><p><strong>Art. 5.-<\/strong> La prueba deber\u00e1 realizarse en bicicleta cl\u00e1sica (bicicletas anteriores a 1996, incluido). En caso contrario no se podr\u00e1 participar en la prueba deportiva.<\/p><p><strong>Art. 6.-<\/strong> La organizaci\u00f3n no se hace responsable de ning\u00fan accidente del que pudiera ser causa o v\u00edctima el participante, que deber\u00e1 estar cubierto por el seguro de accidentes contratado incluida en la inscripci\u00f3n.<\/p><p>Tampoco se hace solidario de los gastos ni las deudas que pudieran contraer los participantes durante la prueba, ni de las p\u00e9rdidas o aver\u00edas que pudieran sufrir las bicicletas u otro equipamiento de los participantes.<\/p><p>El participante exime a la organizaci\u00f3n de cualquier responsabilidad por p\u00e9rdida o deterioro de objetos personales por cualquier circunstancia.<\/p><p><strong>Art. 7.-<\/strong> El organizador garantiza el pleno cumplimiento de la normativa de protecci\u00f3n de datos de car\u00e1cter personal y, as\u00ed, de acuerdo con la Ley Org\u00e1nica 15\/1999, el participante queda informado y presta su consentimiento a la incorporaci\u00f3n de sus datos en los ficheros automatizados existentes por parte del organizador y al tratamiento de los mismos para su utilizaci\u00f3n en relaci\u00f3n con la ejecuci\u00f3n de gestiones administrativas, comerciales y de otras actividades propias.<\/p><p><strong>Art. 8.-<\/strong> La organizaci\u00f3n se reserva el derecho de realizar las modificaciones oportunas, cuando por alg\u00fan motivo lo estime necesario. As\u00ed mismo, se reserva el derecho de admisi\u00f3n.<\/p><p><strong>Art. 9.-<\/strong> Derechos de imagen. La aceptaci\u00f3n del presente reglamento implica obligatoriamente que el participante autoriza a los organizadores de La MTB Classic a la grabaci\u00f3n total o parcial de su participaci\u00f3n en la misma; da su consentimiento para que puedan utilizar su imagen para la promoci\u00f3n y difusi\u00f3n de la imagen de la marcha en todas sus formas (radio, prensa, v\u00eddeo, foto, internet, carteles, medios de comunicaci\u00f3n, etc.), y cede todos los derechos relativos a su explotaci\u00f3n comercial y publicitaria que consideren oportuno ejecutar, sin derecho por su parte a recibir compensaci\u00f3n econ\u00f3mica alguna. Este art\u00edculo se hace extensible tambi\u00e9n a fotograf\u00edas.<\/p><p><strong>Art. 10.-<\/strong> El mero hecho de inscribirse en esta prueba supone la aceptaci\u00f3n del presente reglamento y la renuncia a todos los derechos contra la organizaci\u00f3n, incluyendo tambi\u00e9n la renuncia a toda acci\u00f3n legal que pudiera derivarse de su participaci\u00f3n en la prueba.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca60c7c e-con-full e-flex e-con e-child\" data-id=\"ca60c7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-908f4c1 content-align-left the7-hover-visibility-disabled transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"908f4c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1500\" height=\"1000\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201500%201000&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"Grupo de los participantes de la prueba deportiva de Sea Otter Europe MTB Classic celebrando la carrera bajo el arco de salida\" sizes=\"(max-width: 1500px) 100vw, 1500px\" style=\"--ratio: 1500 \/ 1000;\" data-src=\"https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-030-R-min.jpg\" loading=\"eager\" data-srcset=\"https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-030-R-min.jpg 1500w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-030-R-min-300x200.jpg 300w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-030-R-min-1024x683.jpg 1024w, https:\/\/www.seaottereurope.com\/wp-content\/uploads\/2025\/09\/2025-09-20-mtb-classic-girona-foto-francesc-llado-030-R-min-768x512.jpg 768w\" \/><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nos encantan las tradiciones, \u00a1nos encanta MTB Classic! Ser \u00abold school\u00bb est\u00e1 de moda. Ven\u00a0con tu bicicleta\u00a0cl\u00e1sica y \u00fanete a nosotros\u00a0para hacer historia. Queremos que este legado crezca. Si tienes una bici antes de 1996, no te lo pienses, participa y divi\u00e9rtete, pero si no, ven y disfruta de esas bicis con las que empez\u00f3&hellip;<\/p>\n","protected":false},"author":4,"featured_media":43828,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-44122","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/pages\/44122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/comments?post=44122"}],"version-history":[{"count":31,"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/pages\/44122\/revisions"}],"predecessor-version":[{"id":624060,"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/pages\/44122\/revisions\/624060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/media\/43828"}],"wp:attachment":[{"href":"https:\/\/www.seaottereurope.com\/es\/wp-json\/wp\/v2\/media?parent=44122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}